{"id":17559,"date":"2024-12-13T16:37:38","date_gmt":"2024-12-13T16:37:38","guid":{"rendered":"https:\/\/avecoeur.com\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/"},"modified":"2024-12-17T09:33:28","modified_gmt":"2024-12-17T09:33:28","slug":"villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur","status":"publish","type":"properties","link":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/","title":{"rendered":"Villas et appartements \u00e0 louer \u00e0 Le Clos d&rsquo;Alice, Sainte Maxime, Var, C\u00f4te d&rsquo;Azur"},"excerpt":{"rendered":"<p>Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.<\/p>\n","protected":false},"featured_media":13518,"parent":0,"menu_order":558,"template":"","meta":[],"amenities":[],"areas":[196,374,188,208],"property_types":[263],"contracts":[268],"class_list":["post-17559","properties","type-properties","status-publish","has-post-thumbnail","hentry","areas-provence-alpes-cote-dazur-fr","areas-sainte-maxime-fr","areas-south-of-france-fr","areas-var-fr","property_types-villa-fr","contracts-rent-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Villas et appartements \u00e0 louer \u00e0 Le Clos d&#039;Alice, Sainte Maxime, Var, C\u00f4te d&#039;Azur - Avecoeur<\/title>\n<meta name=\"description\" content=\"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Villas et appartements \u00e0 louer \u00e0 Le Clos d&#039;Alice, Sainte Maxime, Var, C\u00f4te d&#039;Azur - Avecoeur\" \/>\n<meta property=\"og:description\" content=\"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/\" \/>\n<meta property=\"og:site_name\" content=\"Avecoeur\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Avecoeur-100378401788754\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T09:33:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/avecoeur.com\/wp-content\/uploads\/2024\/04\/IMAGE-PISCINE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1808\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/\",\"url\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/\",\"name\":\"Villas et appartements \u00e0 louer \u00e0 Le Clos d'Alice, Sainte Maxime, Var, C\u00f4te d'Azur - Avecoeur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/avecoeur.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMAGE-PISCINE.jpg\",\"datePublished\":\"2024-12-13T16:37:38+00:00\",\"dateModified\":\"2024-12-17T09:33:28+00:00\",\"description\":\"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/avecoeur.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMAGE-PISCINE.jpg\",\"contentUrl\":\"https:\\\/\\\/avecoeur.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/IMAGE-PISCINE.jpg\",\"width\":1808,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/properties\\\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/avecoeur.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Villas et appartements \u00e0 louer \u00e0 Le Clos d&#8217;Alice, Sainte Maxime, Var, C\u00f4te d&#8217;Azur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#website\",\"url\":\"https:\\\/\\\/avecoeur.com\\\/\",\"name\":\"Avecoeur\",\"description\":\"Rent or buy your dream property in France\",\"publisher\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/avecoeur.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#organization\",\"name\":\"Avecoeur\",\"url\":\"https:\\\/\\\/avecoeur.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/avecoeur.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-color.png\",\"contentUrl\":\"https:\\\/\\\/avecoeur.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/logo-color.png\",\"width\":216,\"height\":56,\"caption\":\"Avecoeur\"},\"image\":{\"@id\":\"https:\\\/\\\/avecoeur.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Avecoeur-100378401788754\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Villas et appartements \u00e0 louer \u00e0 Le Clos d'Alice, Sainte Maxime, Var, C\u00f4te d'Azur - Avecoeur","description":"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/","og_locale":"fr_FR","og_type":"article","og_title":"Villas et appartements \u00e0 louer \u00e0 Le Clos d'Alice, Sainte Maxime, Var, C\u00f4te d'Azur - Avecoeur","og_description":"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.","og_url":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/","og_site_name":"Avecoeur","article_publisher":"https:\/\/www.facebook.com\/Avecoeur-100378401788754\/","article_modified_time":"2024-12-17T09:33:28+00:00","og_image":[{"width":1808,"height":1080,"url":"https:\/\/avecoeur.com\/wp-content\/uploads\/2024\/04\/IMAGE-PISCINE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/","url":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/","name":"Villas et appartements \u00e0 louer \u00e0 Le Clos d'Alice, Sainte Maxime, Var, C\u00f4te d'Azur - Avecoeur","isPartOf":{"@id":"https:\/\/avecoeur.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/#primaryimage"},"image":{"@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/#primaryimage"},"thumbnailUrl":"https:\/\/avecoeur.com\/wp-content\/uploads\/2024\/04\/IMAGE-PISCINE.jpg","datePublished":"2024-12-13T16:37:38+00:00","dateModified":"2024-12-17T09:33:28+00:00","description":"Villas et appartements \u00e0 louer dans une r\u00e9sidence avec piscine et jardins \u00e0 Sainte Maxime, \u00e0 proximit\u00e9 de la plage et du centre ville.","breadcrumb":{"@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/#primaryimage","url":"https:\/\/avecoeur.com\/wp-content\/uploads\/2024\/04\/IMAGE-PISCINE.jpg","contentUrl":"https:\/\/avecoeur.com\/wp-content\/uploads\/2024\/04\/IMAGE-PISCINE.jpg","width":1808,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/avecoeur.com\/fr\/properties\/villas-et-appartements-a-louer-a-le-clos-dalice-sainte-maxime-var-cote-dazur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/avecoeur.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Villas et appartements \u00e0 louer \u00e0 Le Clos d&#8217;Alice, Sainte Maxime, Var, C\u00f4te d&#8217;Azur"}]},{"@type":"WebSite","@id":"https:\/\/avecoeur.com\/#website","url":"https:\/\/avecoeur.com\/","name":"Avecoeur","description":"Rent or buy your dream property in France","publisher":{"@id":"https:\/\/avecoeur.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/avecoeur.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/avecoeur.com\/#organization","name":"Avecoeur","url":"https:\/\/avecoeur.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/avecoeur.com\/#\/schema\/logo\/image\/","url":"https:\/\/avecoeur.com\/wp-content\/uploads\/2021\/12\/logo-color.png","contentUrl":"https:\/\/avecoeur.com\/wp-content\/uploads\/2021\/12\/logo-color.png","width":216,"height":56,"caption":"Avecoeur"},"image":{"@id":"https:\/\/avecoeur.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Avecoeur-100378401788754\/"]}]}},"_links":{"self":[{"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/properties\/17559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/types\/properties"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/media\/13518"}],"wp:attachment":[{"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/media?parent=17559"}],"wp:term":[{"taxonomy":"amenities","embeddable":true,"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/amenities?post=17559"},{"taxonomy":"areas","embeddable":true,"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/areas?post=17559"},{"taxonomy":"property_types","embeddable":true,"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/property_types?post=17559"},{"taxonomy":"contracts","embeddable":true,"href":"https:\/\/avecoeur.com\/fr\/wp-json\/wp\/v2\/contracts?post=17559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}